{"id":24260,"date":"2026-09-02T17:22:37","date_gmt":"2026-09-02T15:22:37","guid":{"rendered":"https:\/\/visitfinaleligure.it\/esperienza\/flow-tour-mtb-guide-finale-2\/"},"modified":"2026-09-02T17:22:37","modified_gmt":"2026-09-02T15:22:37","slug":"flow-tour-mtb-guide-finale-2","status":"publish","type":"esperienza","link":"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/","title":{"rendered":"Flow Tour &#8211; MTB GUIDE FINALE"},"content":{"rendered":"<p>Un tour unico su sentieri esclusivi, che solo noi possiamo offrire!<\/p>\n<p>Vi porteremo su territori poco conosciuti, ricchi di miti e leggende e di sentieri spettacolari! Qui i trails sono mantenuti da sapienti mani che lavorano per passione\u2026&nbsp; e per divertirsi poi sulle loro creazioni, ovviamente! <\/p>\n<p>Si parte da Finale Ligure con una risalita in shuttle fino alla Base Nato. Si percorre uno dei sentieri che hanno reso questa localit\u00e0 famosa in tutto il mondo, ma lasceremo presto il glamour di Finale per inoltrarci nel selvaggio est.<\/p>\n<p>Lo shuttle ci aiuter\u00e0 con il trasferimento fino alla Riserva Naturale dell\u2019Adelasia e nelle zone limitrofe, luoghi mistici grazie alle leggende che li popolano, come quella della Principessa Adelasia.<\/p>\n<p>Qui percorreremo i trail mantenuti in perfetto stato dalle associazioni di volontari locali insieme a noi. Sentieri super flow con un tocco naturale, costruiti a regola d\u2019arte, immersi nei boschi di faggi e di querce. <\/p>\n<p>Il livello tecnico dei trail \u00e8 mediamente inferiore rispetto a Finale, grazie al fatto che sono meno battuti e costruiti su terreno pi\u00f9 morbido. Ma sono comunque sentieri adatti ad ogni tipo di rider, da easy al pi\u00f9 esperto.<\/p>\n<p>Dopo aver testato queste meraviglie e aver pranzato in un ristorante tipico con delizie locali, prenderemo la via del ritorno, sempre con assistenza dello shuttle, per rientrare a Finale con uno dei trail come Crestino o Ingegnere.<\/p>\n<p>Scorci meravigliosi vista mare faranno da cornice alla nostra ultima discesa, prima di finire la giornata con una meritata birra a Finale Ligure.<\/p>\n<p><b><br \/><\/b><\/p>\n<p>&nbsp;<\/p>\n<p><\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"tipi_servizi":[],"temi_vacanza":[],"classificazioni":[],"class_list":["post-24260","esperienza","type-esperienza","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flow Tour - MTB GUIDE FINALE - Visit Finale Ligure<\/title>\n<meta name=\"description\" content=\"Un tour unico su sentieri esclusivi, che solo noi possiamo offrire! Vi porteremo su territori poco conosciuti, ricchi di miti e leggende e di sentieri\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flow Tour - MTB GUIDE FINALE - Visit Finale Ligure\" \/>\n<meta property=\"og:description\" content=\"Un tour unico su sentieri esclusivi, che solo noi possiamo offrire! Vi porteremo su territori poco conosciuti, ricchi di miti e leggende e di sentieri\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Finale Ligure\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VisitFinaleLigure\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2026\/08\/image-305.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1706\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/flow-tour-mtb-guide-finale-2\\\/\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/flow-tour-mtb-guide-finale-2\\\/\",\"name\":\"Flow Tour - MTB GUIDE FINALE - Visit Finale Ligure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#website\"},\"datePublished\":\"2026-09-02T15:22:37+00:00\",\"description\":\"Un tour unico su sentieri esclusivi, che solo noi possiamo offrire! Vi porteremo su territori poco conosciuti, ricchi di miti e leggende e di sentieri\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/flow-tour-mtb-guide-finale-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/flow-tour-mtb-guide-finale-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/flow-tour-mtb-guide-finale-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esperienze\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Flow Tour &#8211; MTB GUIDE FINALE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\",\"name\":\"Visit Finale Ligure\",\"description\":\"My perfect place\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#organization\",\"name\":\"Comune di Finale Ligure\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-finaleligure-verticale-positivo-200x200-1.png\",\"contentUrl\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-finaleligure-verticale-positivo-200x200-1.png\",\"width\":512,\"height\":512,\"caption\":\"Comune di Finale Ligure\"},\"image\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VisitFinaleLigure\",\"https:\\\/\\\/www.instagram.com\\\/visitfinale\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLmoLfNmrAt9mSCll9egttw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flow Tour - MTB GUIDE FINALE - Visit Finale Ligure","description":"Un tour unico su sentieri esclusivi, che solo noi possiamo offrire! Vi porteremo su territori poco conosciuti, ricchi di miti e leggende e di sentieri","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/","og_locale":"en_US","og_type":"article","og_title":"Flow Tour - MTB GUIDE FINALE - Visit Finale Ligure","og_description":"Un tour unico su sentieri esclusivi, che solo noi possiamo offrire! Vi porteremo su territori poco conosciuti, ricchi di miti e leggende e di sentieri","og_url":"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/","og_site_name":"Visit Finale Ligure","article_publisher":"https:\/\/www.facebook.com\/VisitFinaleLigure","og_image":[{"width":1706,"height":2560,"url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2026\/08\/image-305.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/","url":"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/","name":"Flow Tour - MTB GUIDE FINALE - Visit Finale Ligure","isPartOf":{"@id":"https:\/\/visitfinaleligure.it\/en\/#website"},"datePublished":"2026-09-02T15:22:37+00:00","description":"Un tour unico su sentieri esclusivi, che solo noi possiamo offrire! Vi porteremo su territori poco conosciuti, ricchi di miti e leggende e di sentieri","breadcrumb":{"@id":"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/visitfinaleligure.it\/en\/esperienza\/flow-tour-mtb-guide-finale-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visitfinaleligure.it\/en\/"},{"@type":"ListItem","position":2,"name":"Esperienze","item":"https:\/\/visitfinaleligure.it\/en\/esperienza\/"},{"@type":"ListItem","position":3,"name":"Flow Tour &#8211; MTB GUIDE FINALE"}]},{"@type":"WebSite","@id":"https:\/\/visitfinaleligure.it\/en\/#website","url":"https:\/\/visitfinaleligure.it\/en\/","name":"Visit Finale Ligure","description":"My perfect place","publisher":{"@id":"https:\/\/visitfinaleligure.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitfinaleligure.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/visitfinaleligure.it\/en\/#organization","name":"Comune di Finale Ligure","url":"https:\/\/visitfinaleligure.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visitfinaleligure.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/04\/cropped-finaleligure-verticale-positivo-200x200-1.png","contentUrl":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/04\/cropped-finaleligure-verticale-positivo-200x200-1.png","width":512,"height":512,"caption":"Comune di Finale Ligure"},"image":{"@id":"https:\/\/visitfinaleligure.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VisitFinaleLigure","https:\/\/www.instagram.com\/visitfinale\/","https:\/\/www.youtube.com\/channel\/UCLmoLfNmrAt9mSCll9egttw"]}]}},"_links":{"self":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/esperienza\/24260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/esperienza"}],"about":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/types\/esperienza"}],"wp:attachment":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/media?parent=24260"}],"wp:term":[{"taxonomy":"tipi_servizi","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/tipi_servizi?post=24260"},{"taxonomy":"temi_vacanza","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/temi_vacanza?post=24260"},{"taxonomy":"classificazioni","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/classificazioni?post=24260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}