{"id":24676,"date":"2026-09-02T17:23:04","date_gmt":"2026-09-02T15:23:04","guid":{"rendered":"https:\/\/visitfinaleligure.it\/esperienza\/for-stickers-2\/"},"modified":"2026-09-02T17:23:04","modified_gmt":"2026-09-02T15:23:04","slug":"for-stickers-2","status":"publish","type":"esperienza","link":"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/","title":{"rendered":"FOR Stickers"},"content":{"rendered":"<p>Collect the fantastic official Outdoor Region Final stickers!<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"tipi_servizi":[],"temi_vacanza":[],"classificazioni":[],"class_list":["post-24676","esperienza","type-esperienza","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FOR Stickers - Visit Finale Ligure<\/title>\n<meta name=\"description\" content=\"Collect the fantastic official Outdoor Region Final stickers!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FOR Stickers - Visit Finale Ligure\" \/>\n<meta property=\"og:description\" content=\"Collect the fantastic official Outdoor Region Final stickers!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Finale Ligure\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VisitFinaleLigure\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2026\/08\/image-490.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"1748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/for-stickers-2\\\/\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/for-stickers-2\\\/\",\"name\":\"FOR Stickers - Visit Finale Ligure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#website\"},\"datePublished\":\"2026-09-02T15:23:04+00:00\",\"description\":\"Collect the fantastic official Outdoor Region Final stickers!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/for-stickers-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/for-stickers-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/for-stickers-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esperienze\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/esperienza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FOR Stickers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\",\"name\":\"Visit Finale Ligure\",\"description\":\"My perfect place\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#organization\",\"name\":\"Comune di Finale Ligure\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-finaleligure-verticale-positivo-200x200-1.png\",\"contentUrl\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-finaleligure-verticale-positivo-200x200-1.png\",\"width\":512,\"height\":512,\"caption\":\"Comune di Finale Ligure\"},\"image\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VisitFinaleLigure\",\"https:\\\/\\\/www.instagram.com\\\/visitfinale\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLmoLfNmrAt9mSCll9egttw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FOR Stickers - Visit Finale Ligure","description":"Collect the fantastic official Outdoor Region Final stickers!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/","og_locale":"en_US","og_type":"article","og_title":"FOR Stickers - Visit Finale Ligure","og_description":"Collect the fantastic official Outdoor Region Final stickers!","og_url":"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/","og_site_name":"Visit Finale Ligure","article_publisher":"https:\/\/www.facebook.com\/VisitFinaleLigure","og_image":[{"width":2480,"height":1748,"url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2026\/08\/image-490.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/","url":"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/","name":"FOR Stickers - Visit Finale Ligure","isPartOf":{"@id":"https:\/\/visitfinaleligure.it\/en\/#website"},"datePublished":"2026-09-02T15:23:04+00:00","description":"Collect the fantastic official Outdoor Region Final stickers!","breadcrumb":{"@id":"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/visitfinaleligure.it\/en\/esperienza\/for-stickers-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visitfinaleligure.it\/en\/"},{"@type":"ListItem","position":2,"name":"Esperienze","item":"https:\/\/visitfinaleligure.it\/en\/esperienza\/"},{"@type":"ListItem","position":3,"name":"FOR Stickers"}]},{"@type":"WebSite","@id":"https:\/\/visitfinaleligure.it\/en\/#website","url":"https:\/\/visitfinaleligure.it\/en\/","name":"Visit Finale Ligure","description":"My perfect place","publisher":{"@id":"https:\/\/visitfinaleligure.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitfinaleligure.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/visitfinaleligure.it\/en\/#organization","name":"Comune di Finale Ligure","url":"https:\/\/visitfinaleligure.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visitfinaleligure.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/04\/cropped-finaleligure-verticale-positivo-200x200-1.png","contentUrl":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/04\/cropped-finaleligure-verticale-positivo-200x200-1.png","width":512,"height":512,"caption":"Comune di Finale Ligure"},"image":{"@id":"https:\/\/visitfinaleligure.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VisitFinaleLigure","https:\/\/www.instagram.com\/visitfinale\/","https:\/\/www.youtube.com\/channel\/UCLmoLfNmrAt9mSCll9egttw"]}]}},"_links":{"self":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/esperienza\/24676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/esperienza"}],"about":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/types\/esperienza"}],"wp:attachment":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/media?parent=24676"}],"wp:term":[{"taxonomy":"tipi_servizi","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/tipi_servizi?post=24676"},{"taxonomy":"temi_vacanza","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/temi_vacanza?post=24676"},{"taxonomy":"classificazioni","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/classificazioni?post=24676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}