{"id":8927,"date":"2022-12-13T10:48:33","date_gmt":"2022-12-13T09:48:33","guid":{"rendered":"https:\/\/visitfinaleligure.it\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/"},"modified":"2025-08-06T16:52:15","modified_gmt":"2025-08-06T14:52:15","slug":"finale-stone-and-monte-cucco","status":"publish","type":"page","link":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/","title":{"rendered":"Finale Stone and Monte Cucco"},"content":{"rendered":"\n\n\t<section class=\"section\" id=\"section_452713163\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_775088895\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:40%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo.jpeg\" class=\"attachment-original size-original\" alt=\"monte cucco\" srcset=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo.jpeg 1600w, https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo-300x225.jpeg 300w, https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo-1024x768.jpeg 1024w, https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo-768x576.jpeg 768w, https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo-1536x1152.jpeg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_775088895 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"is-divider divider clearfix\" ><\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_452713163 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1355892490\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1318574706\">\n\n\n\t<div id=\"col-1886048694\" class=\"col hide-for-small medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1886048694 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1078609618\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-648907409\" class=\"text\">\n\t\t\n\n<p style=\"font-family: 'Rubik'; font-size: 14px; font-weight: 500; color: rgba(39,39,39,0.4);\">FINALE STONE AND MONTE CUCCO<\/p>\n\t\t\n<style>\n#text-648907409 {\n  font-size: 1rem;\n  line-height: 1.5;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2390258021\" class=\"text testi-titolo\">\n\t\t\n\n<h1 class=\"testi-titolo\">Layered limestone<\/h1>\n\t\t\n<style>\n#text-2390258021 {\n  font-size: 2rem;\n  color: rgb(0,0,0);\n}\n#text-2390258021 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-168253548\" class=\"text testi-body\">\n\t\t\n\n<p>In Liguria, the <strong>Finale Stone (&#8220;Pietra di Finale&#8221;)<\/strong> stands as the sole evidence of material from the Miocene Age. The northern and southwestern regions of the Finale area are predominantly covered by a plateau which encompasses valleys like Pora, Aquila, Sciusa, and Rio Cornei.<\/p>\n<p>It is a compact pinkish-white limestone forming impressive vertical walls of up to 200 meters.<\/p>\n<p>&nbsp;<strong>Monte Cucco&nbsp;<\/strong> area is renowned for its distinctive Finale Stone (\u201cPietra di Finale\u201d), making it an ideal spot for sport climbing.<\/p>\n<p>Throughout the centuries, numerous quarries have made significant alterations to the surrounding landscape. No mining operations are being exercised currently.<\/p>\n<p>Sculptors continue choosing Finale Stone for its quality and ability to bring their creative ideas to life.<\/p>\n\t\t\t<\/div>\n\t\n\n  \n    <div id=\"gallery-1597538486\" class=\"row large-columns-2 medium-columns- small-columns- row-collapse row-full-width row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"gallery-col col\" data-animate=\"fadeInLeft\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo_Aria-di-Terra_Finale-Ligure-576x768-1.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-zoom box-shadow-2 image-cover\" style=\"width:67%;padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"768\" src=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo_Aria-di-Terra_Finale-Ligure-576x768-1.jpeg\" class=\"attachment-original size-original\" alt=\"\" ids=\"537,538\" style=\"normal\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"collapse\" columns=\"2\" depth=\"2\" animate=\"fadeInLeft\" image_height=\"100%\" image_width=\"67\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo_Aria-di-Terra_Finale-Ligure-576x768-1.jpeg 576w, https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo_Aria-di-Terra_Finale-Ligure-576x768-1-225x300.jpeg 225w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" data-animate=\"fadeInLeft\">\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo_Caserma-dei-Vigili-del-Fuoco_Finale-Ligure-512x768-1.jpeg\" title=\"\">            <div class=\"box has-hover gallery-box box-normal\">\n              <div class=\"box-image image-zoom box-shadow-2 image-cover\" style=\"width:67%;padding-top:100%;\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"768\" src=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo_Caserma-dei-Vigili-del-Fuoco_Finale-Ligure-512x768-1.jpeg\" class=\"attachment-original size-original\" alt=\"\" ids=\"537,538\" style=\"normal\" lightbox_image_size=\"original\" type=\"masonry\" col_spacing=\"collapse\" columns=\"2\" depth=\"2\" animate=\"fadeInLeft\" image_height=\"100%\" image_width=\"67\" image_size=\"original\" image_hover=\"zoom\" srcset=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo_Caserma-dei-Vigili-del-Fuoco_Finale-Ligure-512x768-1.jpeg 512w, https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo_Caserma-dei-Vigili-del-Fuoco_Finale-Ligure-512x768-1-200x300.jpeg 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1078609618 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n@media (min-width:550px) {\n  #col-1078609618 > .col-inner {\n    margin: -30px 0px 0px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-372260579\" class=\"col hide-for-small medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;margin:0px 0px 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\n\t<script type=\"text\/javascript\">\n  jQuery( document ).ready(function() {\n    function initialize() {\n        var styles = {\n            'flatsome':  [{\n            \"featureType\": \"administrative\",\n            \"stylers\": [\n              { \"visibility\": \"on\" }\n            ]\n          },\n          {\n            \"featureType\": \"road\",\n            \"stylers\": [\n              { \"visibility\": \"on\" },\n              { \"hue\": \"\" }\n            ]\n          },\n          {\n            \"stylers\": [\n\t\t\t  { \"visibility\": \"on\" },\n\t\t\t  { \"hue\": \"\" },\n\t\t\t  { \"saturation\": -30 }\n            ]\n          }\n        ]};\n\n        var myLatlng = new google.maps.LatLng(40.79028, -73.95972);\n        var myOptions = {\n            zoom: 17,\n            center: myLatlng,\n            mapTypeId: google.maps.MapTypeId.ROADMAP,\n            disableDefaultUI: true,\n            mapTypeId: 'flatsome',\n            draggable: true,\n            zoomControl: false,\n            zoomControlOptions: {\n              position: google.maps.ControlPosition.TOP_LEFT\n            },\n      \t\t\tmapTypeControl: false,\n            mapTypeControlOptions: {\n              position: google.maps.ControlPosition.TOP_LEFT\n            },\n      \t\t\tstreetViewControl: false,\n            streetViewControlOptions: {\n              position: google.maps.ControlPosition.TOP_LEFT\n            },\n            scrollwheel: false,\n            disableDoubleClickZoom: true\n        }\n        var map = new google.maps.Map(document.getElementById(\"map-3623570128-inner\"), myOptions);\n        var styledMapType = new google.maps.StyledMapType(styles['flatsome'], {name: 'flatsome'});\n        map.mapTypes.set('flatsome', styledMapType);\n\n        var marker = new google.maps.Marker({\n            position: myLatlng,\n            map: map,\n            title:\"\"\n        });\n    }\n\n    \/\/ Required to proceed\n    if (!(typeof google === 'object' && typeof google.maps === 'object')) {\n      return\n    }\n\n    initialize()\n    google.maps.event.addDomListener(window, 'resize', initialize);\n    });\n    <\/script>\n\n    <div class=\"google-map relative mb\" id=\"map-3623570128\">\n        <div class=\"map-height\" id=\"map-3623570128-inner\"><\/div>\n        <div id=\"map_overlay_top\"><\/div>\n        <div id=\"map_overlay_bottom\"><\/div>\n                  <div class=\"map_inner map-inner last-reset absolute x100 md-x0 lg-x0 y100 md-y0 lg-y0\">\n              \n\n<p><iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d5719.289457673495!2d8.332917!3d44.214383!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x0%3A0x322eec47c50991b3!2sMonte%20Cucco%2C%20La%20Torre%2C%20Rock!5e0!3m2!1sit!2sit!4v1670924428699!5m2!1sit!2sit\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe><\/p>\n\n         <\/div>\n       \n       \n<style>\n#map-3623570128 .map-inner {\n  background-color: #fff;\n  max-width: 100%;\n}\n#map-3623570128 .map-height {\n  height: 400px;\n}\n@media (min-width:550px) {\n  #map-3623570128 .map-inner {\n    max-width: 40%;\n  }\n}\n@media (min-width:850px) {\n  #map-3623570128 .map-inner {\n    max-width: 100%;\n  }\n}\n<\/style>\n    <\/div>\n\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-372260579 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-926796581\" class=\"col hide-for-small medium-1 small-12 large-1\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-926796581 > .col-inner {\n  margin: 0px 0px 0px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1355892490 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":4918,"parent":8887,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-8927","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finale Stone and Monte Cucco - Visit Finale Ligure<\/title>\n<meta name=\"description\" content=\"Explore Pietra di Finale: Miocene limestone shaping Monte Cucco\u2019s cliffs, historic quarries, and sculptures across the region.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finale Stone and Monte Cucco\" \/>\n<meta property=\"og:description\" content=\"The region of Monte Cucco boasts a unique feature in its Finale Stone (&quot;Pietra di Finale&quot;), making it an ideal location for sport climbing.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Finale Ligure\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VisitFinaleLigure\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-06T14:52:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo-1024x768.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/finale-stone-and-monte-cucco\\\/\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/finale-stone-and-monte-cucco\\\/\",\"name\":\"Finale Stone and Monte Cucco - Visit Finale Ligure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/finale-stone-and-monte-cucco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/finale-stone-and-monte-cucco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mario-Nebiolo.jpeg\",\"datePublished\":\"2022-12-13T09:48:33+00:00\",\"dateModified\":\"2025-08-06T14:52:15+00:00\",\"description\":\"Explore Pietra di Finale: Miocene limestone shaping Monte Cucco\u2019s cliffs, historic quarries, and sculptures across the region.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/finale-stone-and-monte-cucco\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/finale-stone-and-monte-cucco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/finale-stone-and-monte-cucco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mario-Nebiolo.jpeg\",\"contentUrl\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Mario-Nebiolo.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/finale-stone-and-monte-cucco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nature\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nature and landscape\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/nature\\\/nature-and-landscape\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Finale Stone and Monte Cucco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\",\"name\":\"Visit Finale Ligure\",\"description\":\"My perfect place\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#organization\",\"name\":\"Comune di Finale Ligure\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-finaleligure-verticale-positivo-200x200-1.png\",\"contentUrl\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-finaleligure-verticale-positivo-200x200-1.png\",\"width\":512,\"height\":512,\"caption\":\"Comune di Finale Ligure\"},\"image\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VisitFinaleLigure\",\"https:\\\/\\\/www.instagram.com\\\/visitfinale\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLmoLfNmrAt9mSCll9egttw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finale Stone and Monte Cucco - Visit Finale Ligure","description":"Explore Pietra di Finale: Miocene limestone shaping Monte Cucco\u2019s cliffs, historic quarries, and sculptures across the region.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/","og_locale":"en_US","og_type":"article","og_title":"Finale Stone and Monte Cucco","og_description":"The region of Monte Cucco boasts a unique feature in its Finale Stone (\"Pietra di Finale\"), making it an ideal location for sport climbing.","og_url":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/","og_site_name":"Visit Finale Ligure","article_publisher":"https:\/\/www.facebook.com\/VisitFinaleLigure","article_modified_time":"2025-08-06T14:52:15+00:00","og_image":[{"url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo-1024x768.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/","url":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/","name":"Finale Stone and Monte Cucco - Visit Finale Ligure","isPartOf":{"@id":"https:\/\/visitfinaleligure.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/#primaryimage"},"image":{"@id":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/#primaryimage"},"thumbnailUrl":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo.jpeg","datePublished":"2022-12-13T09:48:33+00:00","dateModified":"2025-08-06T14:52:15+00:00","description":"Explore Pietra di Finale: Miocene limestone shaping Monte Cucco\u2019s cliffs, historic quarries, and sculptures across the region.","breadcrumb":{"@id":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/#primaryimage","url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo.jpeg","contentUrl":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2022\/12\/Mario-Nebiolo.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/finale-stone-and-monte-cucco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visitfinaleligure.it\/en\/"},{"@type":"ListItem","position":2,"name":"Nature","item":"https:\/\/visitfinaleligure.it\/en\/nature\/"},{"@type":"ListItem","position":3,"name":"Nature and landscape","item":"https:\/\/visitfinaleligure.it\/en\/nature\/nature-and-landscape\/"},{"@type":"ListItem","position":4,"name":"Finale Stone and Monte Cucco"}]},{"@type":"WebSite","@id":"https:\/\/visitfinaleligure.it\/en\/#website","url":"https:\/\/visitfinaleligure.it\/en\/","name":"Visit Finale Ligure","description":"My perfect place","publisher":{"@id":"https:\/\/visitfinaleligure.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitfinaleligure.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/visitfinaleligure.it\/en\/#organization","name":"Comune di Finale Ligure","url":"https:\/\/visitfinaleligure.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visitfinaleligure.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/04\/cropped-finaleligure-verticale-positivo-200x200-1.png","contentUrl":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/04\/cropped-finaleligure-verticale-positivo-200x200-1.png","width":512,"height":512,"caption":"Comune di Finale Ligure"},"image":{"@id":"https:\/\/visitfinaleligure.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VisitFinaleLigure","https:\/\/www.instagram.com\/visitfinale\/","https:\/\/www.youtube.com\/channel\/UCLmoLfNmrAt9mSCll9egttw"]}]}},"_links":{"self":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/pages\/8927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/comments?post=8927"}],"version-history":[{"count":9,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/pages\/8927\/revisions"}],"predecessor-version":[{"id":9687,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/pages\/8927\/revisions\/9687"}],"up":[{"embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/pages\/8887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/media\/4918"}],"wp:attachment":[{"href":"https:\/\/visitfinaleligure.it\/en\/wp-json\/wp\/v2\/media?parent=8927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}