{"id":24113,"date":"2026-08-27T11:20:01","date_gmt":"2026-08-27T09:20:01","guid":{"rendered":"https:\/\/visitfinaleligure.it\/evento\/accademia-in-coro-2\/"},"modified":"2026-08-27T11:20:01","modified_gmt":"2026-08-27T09:20:01","slug":"accademia-in-coro-2","status":"publish","type":"evento","link":"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/","title":{"rendered":"Accademia in coro&#8230;"},"content":{"rendered":"<p>Ch\u0153ur polyphonique de l&#8217;acad\u00e9mie<\/p>\n<p>dirig\u00e9 par M\u00b0 Mattia Pelosi<\/p>\n<p>Mattia Pelosi, t\u00e9nor<\/p>\n<p>Nicholas Tagliantini, basse et piano<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"localita":[195],"temi_vacanza":[1391,1365],"classificazioni":[1393,1368],"eventi_seriali":[],"servizi":[1389],"class_list":["post-24113","evento","type-evento","status-publish","hentry","localita-varigotti","temi_vacanza-adventuresport","temi_vacanza-cultura","classificazioni-adventuresport","classificazioni-cultura","servizi-concerto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Accademia in coro... - Visit Finale Ligure<\/title>\n<meta name=\"description\" content=\"Ch\u0153ur polyphonique de l&#039;acad\u00e9mie dirig\u00e9 par M\u00b0 Mattia Pelosi Mattia Pelosi, t\u00e9nor Nicholas Tagliantini, basse et piano &nbsp;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accademia in coro... - Visit Finale Ligure\" \/>\n<meta property=\"og:description\" content=\"Ch\u0153ur polyphonique de l&#039;acad\u00e9mie dirig\u00e9 par M\u00b0 Mattia Pelosi Mattia Pelosi, t\u00e9nor Nicholas Tagliantini, basse et piano &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Finale Ligure\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VisitFinaleLigure\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/03\/Capo-caprazoppa-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1405\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/evento\\\/accademia-in-coro-2\\\/\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/evento\\\/accademia-in-coro-2\\\/\",\"name\":\"Accademia in coro... - Visit Finale Ligure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/#website\"},\"datePublished\":\"2026-08-27T09:20:01+00:00\",\"description\":\"Ch\u0153ur polyphonique de l'acad\u00e9mie dirig\u00e9 par M\u00b0 Mattia Pelosi Mattia Pelosi, t\u00e9nor Nicholas Tagliantini, basse et piano &nbsp;\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/evento\\\/accademia-in-coro-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/evento\\\/accademia-in-coro-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/evento\\\/accademia-in-coro-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/evento\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Accademia in coro&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/\",\"name\":\"Visit Finale Ligure\",\"description\":\"My perfect place\",\"publisher\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/#organization\",\"name\":\"Comune di Finale Ligure\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-finaleligure-verticale-positivo-200x200-1.png\",\"contentUrl\":\"https:\\\/\\\/visitfinaleligure.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-finaleligure-verticale-positivo-200x200-1.png\",\"width\":512,\"height\":512,\"caption\":\"Comune di Finale Ligure\"},\"image\":{\"@id\":\"https:\\\/\\\/visitfinaleligure.it\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VisitFinaleLigure\",\"https:\\\/\\\/www.instagram.com\\\/visitfinale\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCLmoLfNmrAt9mSCll9egttw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accademia in coro... - Visit Finale Ligure","description":"Ch\u0153ur polyphonique de l'acad\u00e9mie dirig\u00e9 par M\u00b0 Mattia Pelosi Mattia Pelosi, t\u00e9nor Nicholas Tagliantini, basse et piano &nbsp;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Accademia in coro... - Visit Finale Ligure","og_description":"Ch\u0153ur polyphonique de l'acad\u00e9mie dirig\u00e9 par M\u00b0 Mattia Pelosi Mattia Pelosi, t\u00e9nor Nicholas Tagliantini, basse et piano &nbsp;","og_url":"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/","og_site_name":"Visit Finale Ligure","article_publisher":"https:\/\/www.facebook.com\/VisitFinaleLigure","og_image":[{"width":2500,"height":1405,"url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/03\/Capo-caprazoppa-1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/","url":"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/","name":"Accademia in coro... - Visit Finale Ligure","isPartOf":{"@id":"https:\/\/visitfinaleligure.it\/fr\/#website"},"datePublished":"2026-08-27T09:20:01+00:00","description":"Ch\u0153ur polyphonique de l'acad\u00e9mie dirig\u00e9 par M\u00b0 Mattia Pelosi Mattia Pelosi, t\u00e9nor Nicholas Tagliantini, basse et piano &nbsp;","breadcrumb":{"@id":"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/visitfinaleligure.it\/fr\/evento\/accademia-in-coro-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/visitfinaleligure.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/visitfinaleligure.it\/fr\/evento\/"},{"@type":"ListItem","position":3,"name":"Accademia in coro&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/visitfinaleligure.it\/fr\/#website","url":"https:\/\/visitfinaleligure.it\/fr\/","name":"Visit Finale Ligure","description":"My perfect place","publisher":{"@id":"https:\/\/visitfinaleligure.it\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitfinaleligure.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/visitfinaleligure.it\/fr\/#organization","name":"Comune di Finale Ligure","url":"https:\/\/visitfinaleligure.it\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/visitfinaleligure.it\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/04\/cropped-finaleligure-verticale-positivo-200x200-1.png","contentUrl":"https:\/\/visitfinaleligure.it\/wp-content\/uploads\/2023\/04\/cropped-finaleligure-verticale-positivo-200x200-1.png","width":512,"height":512,"caption":"Comune di Finale Ligure"},"image":{"@id":"https:\/\/visitfinaleligure.it\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VisitFinaleLigure","https:\/\/www.instagram.com\/visitfinale\/","https:\/\/www.youtube.com\/channel\/UCLmoLfNmrAt9mSCll9egttw"]}]}},"_links":{"self":[{"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/evento\/24113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/types\/evento"}],"wp:attachment":[{"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/media?parent=24113"}],"wp:term":[{"taxonomy":"localita","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/localita?post=24113"},{"taxonomy":"temi_vacanza","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/temi_vacanza?post=24113"},{"taxonomy":"classificazioni","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/classificazioni?post=24113"},{"taxonomy":"eventi_seriali","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/eventi_seriali?post=24113"},{"taxonomy":"servizi","embeddable":true,"href":"https:\/\/visitfinaleligure.it\/fr\/wp-json\/wp\/v2\/servizi?post=24113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}